{"id":2562,"date":"2024-09-07T15:01:47","date_gmt":"2024-09-07T13:01:47","guid":{"rendered":"https:\/\/art-restauro.de\/?page_id=2562"},"modified":"2025-07-20T19:33:38","modified_gmt":"2025-07-20T17:33:38","slug":"aktuelles","status":"publish","type":"page","link":"https:\/\/art-restauro.de\/en\/aktuelles\/","title":{"rendered":"Latest news"},"content":{"rendered":"\n<div id=\"attachment_2594\" style=\"width: 484px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2594\" class=\" wp-image-2594\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558-206x300.jpeg\" alt=\"3D- Projekt im Historischen Museum Bielefeld\" width=\"474\" height=\"690\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558-206x300.jpeg 206w, https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558-703x1024.jpeg 703w, https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558-768x1118.jpeg 768w, https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558-1055x1536.jpeg 1055w, https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/IMG_7558.jpeg 1179w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><p id=\"caption-attachment-2594\" class=\"wp-caption-text\">Antwerpener Schnitzaltar der Altst\u00e4dter Nicolaikirche als faszinierendes 3D- Modell<\/p><\/div>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-7109b729-f6be-42f3-9e0c-f3a314ab93d5\" href=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/MG_2881.jpg\">Abbildung von Retabel<\/a><a class=\"wp-block-file__button wp-element-button\" href=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2024\/09\/MG_2881.jpg\" download=\"\" aria-describedby=\"wp-block-file--media-7109b729-f6be-42f3-9e0c-f3a314ab93d5\">Herunterladen<\/a><\/div>\n<p><\/p>\n<p>\u00a0<\/p>\n<p><strong>EINLADUNG<\/strong><\/p>\n<p><strong>500 Jahre Antwerpener Schnitzaltar der Ev. Altst\u00e4dter Nicolaikirche zu Bielefeld<\/strong><\/p>\n<p>Der sp\u00e4tgotischer Schnitzaltar von 1524 geh\u00f6rt zum Besten, was die Antwerpener Schnitz- und Malkunst im fr\u00fchen 16. Jahrhundert hervorgebracht hat. Mit neun Schreinen im geschnitzten Mittelteil und mit 24 Bildtafeln auf den Innen- und Au\u00dfenseiten der Fl\u00fcgel, erreicht das Werk 6,44 Meter in der Breite und 4,46 Meter in der H\u00f6he.<\/p>\n<p>Antwerpener Retabel kunsthistorisch betrachtet und interpretiert<\/p>\n<p>W\u00e4hrend der Restaurierungsarbeiten im Jahre 2022 wurden hochwertige 3D-Aufnahmen des ganzen Altars in Auftrag gegeben. Zum Jubil\u00e4um sollen sie der Stadtgesellschaft dauerhaft in der Mittelalter-Abteilung des <strong>Historischen Museums in Bielefeld<\/strong> zug\u00e4nglich und erlebbar gemacht werden.<\/p>\n<p>Durch dieses <strong>einmalige 3D- Projekt<\/strong> m\u00f6chten wir unseren Freunden, Kunstinteressierten und dem Fachpublikum den Schnitzaltar n\u00e4herbringen. Auf einem Multi- Touch- Bildschirm und mit der 3D- Brille kann der Betrachter die feinen Details der geschnitzten Figuren, deren farbige Polychromie und die feinen Malereien der Tafelbilder aus der N\u00e4he erleben. Es ist faszinierend, in die Zeit der Hochgotik, in diese farbige und lebendige Welt und in deren Geschichte einzutauchen.<\/p>\n<p>Das Projekt ist in Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, mit einigen Fotos und Dokumentationen, die bei der Restaurierung angefertigt worden sind und viel Engagement einzelner Freund*innen des Altars, entstanden.Wir m\u00f6chten Sie auf diese Zeitreise gerne mitnehmen\u2026.. Kommen Sie bitte mit!<\/p>\n<p>Die Pr\u00e4sentation und Erstauff\u00fchrung wurde am <strong>Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld<\/strong> aufgef\u00fchrt.<\/p>\n<p>altar@historisches-museum-bielefeld.de<\/p>\n<p><strong>VORTR\u00c4GE:<\/strong><\/p>\n<p><strong>Samstag, 14. September 2024, 15.00 bis 16.30 Uhr.<\/strong> Der Referent Dr. Hanke Tammen erl\u00e4utert aus kunsthistorischer Perspektive die Bedeutung. F\u00fcr den anschlie\u00dfenden Austausch wird Restauratorin Ludmila Henseler die Veranstaltung begleiten und ihre Expertise einbringen.<\/p>\n<p><strong>Hinter die Kulissen geschaut\/\/ Konservierung und Restaurierung des Antwerpener Schnitzaltars:<\/strong><\/p>\n<p><strong>Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr:<\/strong> Die Referentin Ludmila Henseler (Diplom-Restauratorin) gemeinsam mit Ute Westedt (Diplom-Restauratorin)<\/p>\n<p>Sie geben die Einblicke in ihre Arbeit als Restauratorinnen und laden ein zur Besichtigung mit Erl\u00e4uterungen und anschlie\u00dfendem Austausch<\/p>\n<p><strong>Ort: Altst\u00e4dter Nicolaikirche, Bielefeld<\/strong><\/p>\n<p>Weitere Veranstaltungen finden Sie unter: 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Draiflessen Collection Mettingen<\/strong><\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1.jpg\" alt=\"\" class=\"wp-image-2729\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1.jpg 800w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1-300x300.jpg 300w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1-150x150.jpg 150w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1-768x768.jpg 768w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1-12x12.jpg 12w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/VuVUdO-EGvB_-Quadrate2-1-400x400.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-1024x768.jpg\" alt=\"\" class=\"wp-image-2731\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-1024x768.jpg 1024w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-300x225.jpg 300w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-768x576.jpg 768w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-16x12.jpg 16w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634-400x300.jpg 400w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/07\/Draiflessen_Unter_der_Oberflaeche_5634.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n<p><strong>OPEN UP! Unter der Oberfl\u00e4che <br><\/strong><strong>Tafelbilder und ihre Geheimnisse<\/strong><\/p>\n<p>Altmeisterliche Gem\u00e4lde faszinieren uns seit Jahrhunderten. Ihre detaillierte Handwerkskunst und die Verwendung meisterhafter Farben, Materialien und Techniken lassen uns staunen. Doch was liegt unter der Oberfl\u00e4che dieser Kunstwerke? Bei genauerer Betrachtung offenbaren sich oft versteckte Symbole und Botschaften, die K\u00fcnstler in ihre Werke integrierten. Diese waren f\u00fcr die Menschen der damaligen Zeit allgemein verst\u00e4ndlich, f\u00fcr uns erschlie\u00dfen sie sich heute h\u00e4ufig nicht mehr und lassen sich nur durch die Analyse der historischen und kulturellen Kontexte entschl\u00fcsseln. So werden die Kunstwerke zu komplexen Puzzles, die darauf warten, gel\u00f6st zu werden.<br><br>Das Magazin OPEN UP! ist eine Einladung, unsere Sinne zu sch\u00e4rfen und unsere Interpretationsf\u00e4higkeiten zu erweitern, innezuhalten und die verborgenen Sch\u00e4tze zu entdecken, die unter der Oberfl\u00e4che liegen.<br><br><strong>Herausgeber*in<\/strong><br>Draiflessen Collection<br><br><strong>Autor*innen<\/strong><br>Martin Rudolf Brenninkmeijer, Dr. Julia Cwojdzinski, Ludmila Henseler, Dr. Corinna Otto, Ruth Rasche, Nicole Roth<br><br>\u20ac 9,50<br>ISBN 978-3-942359-65-8 (DE, NL, EN)<\/p>\n\n\n\n<div id=\"attachment_2630\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2630\" class=\"size-medium wp-image-2630\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185057-300x206.png\" alt=\"Draiflessen Collection\" width=\"300\" height=\"206\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185057-300x206.png 300w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185057-1024x704.png 1024w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185057-768x528.png 768w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185057.png 1164w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-2630\" class=\"wp-caption-text\">Unter der Oberfl\u00e4che, Tafelbilder und ihre Geheimnisse<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2631\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185144-183x300.png\" alt=\"\" width=\"183\" height=\"300\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185144-183x300.png 183w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185144.png 487w\" sizes=\"auto, (max-width: 183px) 100vw, 183px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2632\" src=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-300x204.png\" alt=\"\" width=\"300\" height=\"204\" srcset=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-300x204.png 300w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-1024x697.png 1024w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-768x523.png 768w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-1536x1045.png 1536w, https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-19-185319-2048x1393.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>&nbsp;<\/p>\n<p><a href=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2025\/05\/Draiflessen-Collection-in-Mettingen-bei-Osnabrueck-1.pdf\">Draiflessen Collection in Mettingen bei Osnabr\u00fcck<\/a><\/p>\n\n\n\n<p>2009 gr\u00fcndete die Unternehmer*innenfamilie Brenninkmeijer in ihrer westf\u00e4lischen Heimat Mettingen Draiflessen. Auf dem ehemaligen Produktionsgel\u00e4nde entstand neben dem modernen Konferenzzentrum ein nach h\u00f6chsten internationalen Standards geplantes Museum, die Draiflessen Collection, mit Pr\u00e4sentationsfl\u00e4chen f\u00fcr hochkar\u00e4tige Wechselausstellungen sowie modernsten Archiv- und Depotr\u00e4umen. Den Besucher*innen bieten sich im Museum drei verschiedene Bereiche: Die Hauptausstellungsfl\u00e4che (Main Space) mit wechselnden Pr\u00e4sentationen k\u00fcnstlerischer Arbeiten und internationaler Leihgaben, der Studiensaal mit der Liberna Collection und wechselnden Ausstellungen aus dem herausragenden Bestand an Buchkunst und Grafik mit Schwerpunkt im 15. und 17. Jahrhundert sowie DAS Forum als Plattform f\u00fcr die Familienunternehmensforschung, das Einblicke in die wissenschaftliche Arbeit mit Archiv und Sammlung pr\u00e4sentiert. Bitte beachten: Da unsere Sammlungen nicht dauerhaft in einer st\u00e4ndigen Ausstellung pr\u00e4sentiert werden k\u00f6nnen, stellen wir ausgew\u00e4hlte Objekte aus Kunst und Unternehmen online genauer vor und geben so einen Einblick, was sich in unseren Depots befindet. Von Beginn an ist die Draiflessen Collection als ein Ort der Begegnung gedacht. Es geht darum, Erfahrungen auszutauschen und weiterzugeben, ebenso wie andere Perspektiven kennenzulernen und anzuerkennen. Alle Ausstellungen werden durch ein umfangreiches Programm von Vermittlungsangeboten, Workshops und Exkursionen f\u00fcr Menschen unterschiedlichen Alters sowie k\u00f6rperlicher und geistiger F\u00e4higkeiten begleitet. Die Vorfahren der Gr\u00fcnder*innenfamilie Brenninkmeijer geh\u00f6rten den sogenannten T\u00fc\u00f6tten an, westf\u00e4lische Wanderh\u00e4ndler, die vor allem im 17. und 18. Jahrhundert durch Deutschland und Nordeuropa zogen, um mit Leinen Handel zu treiben. In der Wahl des Standorts f\u00fcr Draiflessen hat die Unternehmer*innenfamilie bewusst an ihre westf\u00e4lischen Wurzeln und ihren Heimatort Mettingen angekn\u00fcpft. Gleichzeitig war damit die Entscheidung verbunden, mit einem Kunstmuseum abseits der Metropolen das Angebot an kulturellen Einrichtungen in der Region zu erweitern.<br><br>Der Name \u201eDraiflessen\u201c [d\u0281a\u02d0\u02c8fl\u025bsn] ist eine Wortkonstruktion, die aus der alten Geheimsprache der T\u00fc\u00f6tten abgeleitet wurde. In seinen beiden Wortst\u00e4mmen \u201edrai\u201c (Bedeutung: drei, Dreifaltigkeit, drehen, Handel treiben) und \u201eflessen\u201c (Bedeutung: Flachs, Leinen, Heimat) kommen f\u00fcr die Gr\u00fcnderfamilie bedeutsame Themen zum Ausdruck: ihre enge Verbindung mit ihren westf\u00e4lischen Urspr\u00fcngen, ihr christlicher Glaube und ihr Unternehmer*innentum, das seinerzeit im Textilhandel seinen Anfang genommen hat.<\/p>\n<p><br>Adresse:<br>www.draiflessen.com<br>Draiflessen Collection<br>Georgstr. 18<br>49497 Mettingen<br>Tel.: +49 (0)5452. 91 68-3500<br>info@draiflessen.com<\/p>\n<p><br>\u00d6ffnungszeiten<br>Mittwoch &#8211; Sonntags<br>von 11 bis 17 Uhr<br>jeder erste Donnerstag im Monat<br>von 11 bis 21 Uhr<br>Montags und Dienstags geschlossen<br>\u00a9 Draiflessen Collection<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>500 Jahre Antwerpener Schnitzaltar in Bielefeld<\/p>","protected":false},"author":5,"featured_media":988,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2562","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktuelles - ART RESTAURO<\/title>\n<meta name=\"description\" content=\"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \/\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/art-restauro.de\/en\/aktuelles\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktuelles - ART RESTAURO\" \/>\n<meta property=\"og:description\" content=\"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \/\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/art-restauro.de\/en\/aktuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"ART RESTAURO\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-20T17:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/Altar-Gesamtaufnahme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/\",\"url\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/\",\"name\":\"Aktuelles - ART RESTAURO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/art-restauro.de\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Altar-Gesamtaufnahme.jpg\",\"datePublished\":\"2024-09-07T13:01:47+00:00\",\"dateModified\":\"2025-07-20T17:33:38+00:00\",\"description\":\"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \\\/\\\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/art-restauro.de\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Altar-Gesamtaufnahme.jpg\",\"contentUrl\":\"https:\\\/\\\/art-restauro.de\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Altar-Gesamtaufnahme.jpg\",\"width\":1024,\"height\":661,\"caption\":\"500-tes Altarjubil\u00e4um Altwerpener Schnitzaltar zu Bielefeld Feierlichkeiten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/aktuelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/art-restauro.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#website\",\"url\":\"https:\\\/\\\/art-restauro.de\\\/\",\"name\":\"ART RESTAURO\",\"description\":\"Restaurierung von Gem\u00e4lden, Alt\u00e4ren, Tafelbildern und Holzplastiken\",\"publisher\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/art-restauro.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#organization\",\"name\":\"ART RESTAURO\",\"url\":\"https:\\\/\\\/art-restauro.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/art-restauro.de\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ar-favicon.png\",\"contentUrl\":\"https:\\\/\\\/art-restauro.de\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ar-favicon.png\",\"width\":60,\"height\":60,\"caption\":\"ART RESTAURO\"},\"image\":{\"@id\":\"https:\\\/\\\/art-restauro.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktuelles - ART RESTAURO","description":"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \/\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/art-restauro.de\/en\/aktuelles\/","og_locale":"en_GB","og_type":"article","og_title":"Aktuelles - ART RESTAURO","og_description":"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \/\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)","og_url":"https:\/\/art-restauro.de\/en\/aktuelles\/","og_site_name":"ART RESTAURO","article_modified_time":"2025-07-20T17:33:38+00:00","og_image":[{"width":1024,"height":661,"url":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/Altar-Gesamtaufnahme.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/art-restauro.de\/aktuelles\/","url":"https:\/\/art-restauro.de\/aktuelles\/","name":"Aktuelles - ART RESTAURO","isPartOf":{"@id":"https:\/\/art-restauro.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/art-restauro.de\/aktuelles\/#primaryimage"},"image":{"@id":"https:\/\/art-restauro.de\/aktuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/Altar-Gesamtaufnahme.jpg","datePublished":"2024-09-07T13:01:47+00:00","dateModified":"2025-07-20T17:33:38+00:00","description":"500 j\u00e4hriges Jubil\u00e4um des Antwerpener Schnitzaltars aus der Altst\u00e4dter St. Nicolaikirche in Bielefeld EINLADUNG 500 Jahre Antwerpener Altar der Altst\u00e4dter Nicolaikirche \/\/ Vortr\u00e4ge Restaurierungsarbeiten 3D-Aufnahmen des ganzen Altars 3D- Projekt 3D- Brille Kooperation mit dem Historischen Museum in Bielefeld, mit dem F\u00f6rderkreis Altst\u00e4dter Nicolaikirche FAN, mit der Firma F7-Digital aus Leipzig, Pr\u00e4sentation und Erstauff\u00fchrung wird am Freitag, den 13. September 2024 (ab 11:00) in den R\u00e4umlichkeiten des Historischen Museums in Bielefeld stattfinden. altar@historisches-museum-bielefeld.de VORTR\u00c4GE: Samstag, 14. September 2024, 15.00 bis 16.30 Uhr. Der Referent Dr. Hanke Tammen Restauratorin Ludmila Henseler Konservierung und Restaurierung des Antwerpener Schnitzaltars: Sonntag, 15. September 2024, 15.00 bis 17.00 Uhr: Die Referentin Ludmila Henseler (Diplom-Restauratorin) Ute Westedt (Diplom-Restauratorin) Ort: Altst\u00e4dter Nicolaikirche, Bielefeld 500 Jahre Antwerpener Altar \u2013 Evangelischer Kirchenkreis Bielefeld (kirche-bielefeld.de)","breadcrumb":{"@id":"https:\/\/art-restauro.de\/aktuelles\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/art-restauro.de\/aktuelles\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/art-restauro.de\/aktuelles\/#primaryimage","url":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/Altar-Gesamtaufnahme.jpg","contentUrl":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/Altar-Gesamtaufnahme.jpg","width":1024,"height":661,"caption":"500-tes Altarjubil\u00e4um Altwerpener Schnitzaltar zu Bielefeld Feierlichkeiten"},{"@type":"BreadcrumbList","@id":"https:\/\/art-restauro.de\/aktuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/art-restauro.de\/"},{"@type":"ListItem","position":2,"name":"Aktuelles"}]},{"@type":"WebSite","@id":"https:\/\/art-restauro.de\/#website","url":"https:\/\/art-restauro.de\/","name":"ART RESTAURO","description":"Restaurierung von Gem\u00e4lden, Alt\u00e4ren, Tafelbildern und Holzplastiken","publisher":{"@id":"https:\/\/art-restauro.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/art-restauro.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/art-restauro.de\/#organization","name":"ART RESTAURO","url":"https:\/\/art-restauro.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/art-restauro.de\/#\/schema\/logo\/image\/","url":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/ar-favicon.png","contentUrl":"https:\/\/art-restauro.de\/wp-content\/uploads\/2016\/01\/ar-favicon.png","width":60,"height":60,"caption":"ART RESTAURO"},"image":{"@id":"https:\/\/art-restauro.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/pages\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":9,"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/pages\/2562\/revisions"}],"predecessor-version":[{"id":2741,"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/pages\/2562\/revisions\/2741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/media\/988"}],"wp:attachment":[{"href":"https:\/\/art-restauro.de\/en\/wp-json\/wp\/v2\/media?parent=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}